{"id":18257,"date":"2016-06-14T06:15:58","date_gmt":"2016-06-14T05:15:58","guid":{"rendered":"https:\/\/www.clarkdoor.com\/contactar-a-clark-door\/"},"modified":"2023-06-19T16:27:34","modified_gmt":"2023-06-19T15:27:34","slug":"contactar-a-clark-door","status":"publish","type":"page","link":"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/","title":{"rendered":"Contactar a Clark Door"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; parallax=&#8221;content-moving&#8221; parallax_image=&#8221;6442&#8243; wrap_container=&#8221;yes&#8221; el_class=&#8221;half-right no-padding border-top-1&#8243; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;js&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; section_skin=&#8221;primary&#8221; section_skin_scale=&#8221;scale-2&#8243; css=&#8221;.vc_custom_1555338048490{padding-right: 80px !important;}&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;]<style type=\"text\/css\">@media only screen and (min-width: 1300px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 650px; }  } @media only screen and (max-width: 1299px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 541.66666666667px; }  } @media only screen and (max-width: 1000px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 464.28571428571px; }  } @media only screen and (max-width: 690px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 240.74074074074px; }  } <\/style><div data-midnight=\"nectar-slider\" class=\"parallax_slider_outer \"><div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"\" data-parallax=\"true\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"true\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"false\" data-height=\"650\" data-min-height=\"\" data-arrows=\"false\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg lazyload\" style=\"background-image:inherit;\" data-bg-image=\"url(https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/09\/R0A9205-1.jpg)\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">Contate-nos<\/h2><p  ><span>Entre em contacto para discutir o seu projeto.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; parallax=&#8221;content-moving&#8221; parallax_image=&#8221;6442&#8243; wrap_container=&#8221;yes&#8221; el_class=&#8221;half-right no-padding border-top-1&#8243; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;js&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; section_skin=&#8221;primary&#8221; section_skin_scale=&#8221;scale-2&#8243; css=&#8221;.vc_custom_1555338048490{padding-right: 80px !important;}&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Contactar-nos&#8221; font_container=&#8221;tag:h1|font_size:32px|text_align:left|line_height:50px&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221;]A equipe de especialistas da Clark Door est\u00e1 dispon\u00edvel para ajudar. Entre em contato conosco por telefone, email ou preencha o formul\u00e1rio de contato abaixo se precisar de mais informa\u00e7\u00f5es sobre a nossa ampla gama de portas especiais.[\/vc_column_text][vc_custom_heading text=&#8221;Sede e F\u00e1brica &#8211; Carlisle, Reino Unido&#8221; font_container=&#8221;tag:h1|font_size:22x|text_align:left|line_height:50px&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; el_class=&#8221;mb-2 text-md-left&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-home\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> <strong>Endere\u00e7o:<\/strong> Unit F Central, Kingmoor Park, Carlisle, CA6 4SD, United Kingdom <\/div><div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-phone\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> <strong>Telefone:<\/strong> +441228522321 <\/div><div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-phone\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> Correio <strong>eletr\u00f3nico: <\/strong>mail@clarkdoor.com <\/div>[vc_custom_heading text=&#8221;MENA Escrit\u00f3rio &#8211; Dubai, Emirados \u00c1rabes Unidos&#8221; font_container=&#8221;tag:h1|font_size:22x|text_align:left|line_height:50px&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; el_class=&#8221;mb-2 text-md-left&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-home\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> <strong>Endere\u00e7o: <\/strong>501, 5th Floor, Bloco B, Business Village, Port Saeed, Deira, Dubai, EAU <\/div><div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-phone\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> <strong>Telefone:<\/strong> +971 600 575 264 <\/div><div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-phone\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> Correio <strong>eletr\u00f3nico: <\/strong>mail@clarkdoor.com <\/div>[vc_custom_heading text=&#8221;Hor\u00e1rio comercial&#8221; font_container=&#8221;tag:h1|font_size:22x|text_align:left|line_height:50px&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; el_class=&#8221;mb-2 text-md-left&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"dot\" data-animation=\"true\" data-animation-delay=\"0\" data-spacing=\"default\" data-alignment=\"left\"> <strong>Segunda a Quinta:<\/strong> 08:30 &#8211; 16:50 Local <\/div><div class=\"nectar-fancy-ul\" data-list-icon=\"dot\" data-animation=\"true\" data-animation-delay=\"0\" data-spacing=\"default\" data-alignment=\"left\"> <strong>Sexta-feira<\/strong> 08:30 &#8211; 16:30 Local <\/div><div class=\"nectar-fancy-ul\" data-list-icon=\"dot\" data-animation=\"true\" data-animation-delay=\"0\" data-spacing=\"default\" data-alignment=\"left\"> <strong>S\u00e1bado e domingo<\/strong> &#8211; Fechado <\/div>[\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]<div class='fluentform ff-default fluentform_wrapper_9 ffs_default_wrap'><form data-form_id=\"9\" id=\"fluentform_9\" class=\"frm-fluent-form fluent_form_9 ff-el-form-top ff_form_instance_9_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_9_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Main Contact Form - Portuguese<\/legend>        <div\n                style=\"display: none!important; position: absolute!important; transform: translateX(1000%)!important;\"\n                class=\"ff-el-group ff-hpsf-container\"\n        >\n            <div class=\"ff-el-input--label asterisk-right\">\n                <label for=\"ff_9_item_sf\" aria-label=\"Notify\">\n                    Notify                <\/label>\n            <\/div>\n            <div class=\"ff-el-input--content\">\n                <input type=\"text\"\n                       name=\"item_9__fluent_sf\"\n                       class=\"ff-el-form-control\"\n                       id=\"ff_9_item_sf\"\n                \/>\n            <\/div>\n        <\/div>\n        <input type='hidden' name='__fluent_form_embded_post_id' value='18291' \/><input type=\"hidden\" id=\"_fluentform_9_fluentformnonce\" name=\"_fluentform_9_fluentformnonce\" value=\"6a725c95a6\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/pt-br\/wp-json\/wp\/v2\/pages\/18257\" \/><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_9_names_first_name_' id='label_ff_9_names_first_name_' >Primeiro nome<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_9_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Primeiro nome\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_9_names_last_name_' id='label_ff_9_names_last_name_' >Sobrenome<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_9_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Sobrenome\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_9_email' id='label_ff_9_email' aria-label=\"Email\">Email<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_9_email\" class=\"ff-el-form-control\" placeholder=\"E-mail\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_9_input_text' id='label_ff_9_input_text' aria-label=\"N\u00famero de telefone\">N\u00famero de telefone<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" data-name=\"input_text\" id=\"ff_9_input_text\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_9_input_text_3' id='label_ff_9_input_text_3' aria-label=\"Empresa\">Empresa<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_3\" class=\"ff-el-form-control\" data-name=\"input_text_3\" id=\"ff_9_input_text_3\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_9_dropdown' id='label_ff_9_dropdown' aria-label=\"Como voc\u00ea nos descobriu?\">Como voc\u00ea nos descobriu?<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown\" id=\"ff_9_dropdown\" class=\"ff-el-form-control\" data-name=\"dropdown\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_9_dropdown\"><option value=\"\">- Select -<\/option><option value=\"Cliente existente\"  >Cliente existente<\/option><option value=\"Recomenda\u00e7\u00e3o\"  >Recomenda\u00e7\u00e3o<\/option><option value=\"Especifica\u00e7\u00e3o\"  >Especifica\u00e7\u00e3o<\/option><option value=\"E-mail\"  >E-mail<\/option><option value=\"Comunicado de Imprensa\/Publica\u00e7\u00e3o\"  >Comunicado de Imprensa\/Publica\u00e7\u00e3o<\/option><option value=\"Pesquisa do Google\"  >Pesquisa do Google<\/option><option value=\"LinkedIn\"  >LinkedIn<\/option><option value=\"Algo mais\"  >Algo mais<\/option><\/select><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_9_dropdown_1' id='label_ff_9_dropdown_1' aria-label=\"Assunto\">Assunto<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown_1\" id=\"ff_9_dropdown_1\" class=\"ff-el-form-control\" data-name=\"dropdown_1\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_9_dropdown_1\"><option value=\"\">- Select -<\/option><option value=\"Nova cota\u00e7\u00e3o de porta\"  >Nova cota\u00e7\u00e3o de porta<\/option><option value=\"Consulta T\u00e9cnica\"  >Consulta T\u00e9cnica<\/option><option value=\"Consulta de servi\u00e7o\"  >Consulta de servi\u00e7o<\/option><option value=\"Algo mais\"  >Algo mais<\/option><\/select><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_9_message' id='label_ff_9_message' aria-label=\"Sua mensagem\">Sua mensagem<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_9_message\" name=\"message\" id=\"ff_9_message\" class=\"ff-el-form-control\" placeholder=\"Sua mensagem\" rows=\"4\" cols=\"2\" data-name=\"message\" ><\/textarea><\/div><\/div><div class='ff-el-group    ff-el-input--content'><div class='ff-el-form-check ff-el-tc'><label aria-label='Termos e condi\u00e7\u00f5es: Posso confirmar que li e aceito o privacy &amp; cookies policy. Cont\u00e9m 1 link. Use a navega\u00e7\u00e3o por abas para revisar.' class='ff-el-form-check-label ff_tc_label' for=terms-n-condition_4679d8d5435989fd22628901b26c7a25><span class='ff_tc_checkbox'><input type=\"checkbox\" name=\"terms-n-condition\" class=\"ff-el-form-check-input\" data-name=\"terms-n-condition\" id=\"terms-n-condition_4679d8d5435989fd22628901b26c7a25\"  value='on' aria-invalid='false' aria-required=false><\/span> <div class='ff_t_c'><p>Posso confirmar que li e aceito o <a href=\"https:\/\/www.clarkdoor.com\/privacy-policy\/\">privacy &amp; cookies policy.<\/a><\/p><\/div><\/label><\/div><\/div><div class='ff-el-group    ff-el-input--content'><div class='ff-el-form-check ff-el-tc'><label aria-label='Eu concordo que este site armazene minhas informa\u00e7\u00f5es enviadas para que possam responder \u00e0 minha consulta.' class='ff-el-form-check-label ff_tc_label' for=gdpr-agreement_c521dc5148aaef8525448bb48a0ff27e><span class='ff_tc_checkbox'><input type=\"checkbox\" name=\"gdpr-agreement\" class=\"ff-el-form-check-input ff_gdpr_field\" data-name=\"gdpr-agreement\" id=\"gdpr-agreement_c521dc5148aaef8525448bb48a0ff27e\"  value='on' aria-invalid='false' aria-required=true><\/span> <div class='ff_t_c'>Eu concordo que este site armazene minhas informa\u00e7\u00f5es enviadas para que possam responder \u00e0 minha consulta.<\/div><\/label><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><\/form><div id='fluentform_9_errors' class='ff-errors-in-stack ff_form_instance_9_1 ff-form-loading_errors ff_form_instance_9_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_9_1 = {\"id\":\"9\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_9_1\",\"form_id_selector\":\"fluentform_9\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"Este campo \\u00e9 obrigat\\u00f3rio\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}},\"names[last_name]\":{\"required\":{\"value\":true,\"message\":\"Este campo \\u00e9 obrigat\\u00f3rio\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"Este campo \\u00e9 obrigat\\u00f3rio\"},\"email\":{\"value\":true,\"message\":\"Este campo deve conter um e-mail v\\u00e1lido\"}},\"input_text\":{\"required\":{\"value\":true,\"message\":\"Este campo \\u00e9 obrigat\\u00f3rio\"}},\"input_text_3\":{\"required\":{\"value\":true,\"message\":\"Este campo \\u00e9 obrigat\\u00f3rio\"}},\"dropdown\":{\"required\":{\"value\":true,\"message\":\"Este campo \\u00e9 obrigat\\u00f3rio\"}},\"dropdown_1\":{\"required\":{\"value\":true,\"message\":\"Este campo \\u00e9 obrigat\\u00f3rio\"}},\"message\":{\"required\":{\"value\":true,\"message\":\"Este campo \\u00e9 obrigat\\u00f3rio\"}},\"terms-n-condition\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}},\"gdpr-agreement\":{\"required\":{\"value\":true,\"message\":\"This field is required\"}}},\"debounce_time\":300};\n                            <\/script>\n            [\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;custom&#8221; custom_text_color=&#8221;#ffffff&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; wrap_container=&#8221;yes&#8221; is_section=&#8221;yes&#8221; section_skin=&#8221;primary&#8221; remove_margin_top=&#8221;yes&#8221; remove_margin_bottom=&#8221;yes&#8221; remove_border=&#8221;yes&#8221; el_class=&#8221;home-intro home-intro-dark&#8221; css=&#8221;.vc_custom_1555499835658{padding-top: 60px !important;padding-bottom: 60px !important;}&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#003d7f&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_gmap map_type=&#8221;leaflet&#8221; zoom=&#8221;3&#8243; marker_style=&#8221;nectar&#8221; color=&#8221;accent-color&#8221; size=&#8221;700&#8243; map_center_lat=&#8221;54.926&#8243; map_center_lng=&#8221;-2.973&#8243; map_markers=&#8221;54.926|-2.973|Our Location 25.192|55.275|Our Dubai Office&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; vertically_center_columns=&#8221;true&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#003d7f&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;custom&#8221; custom_text_color=&#8221;#ffffff&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; wrap_container=&#8221;yes&#8221; is_section=&#8221;yes&#8221; section_skin=&#8221;primary&#8221; remove_margin_top=&#8221;yes&#8221; remove_margin_bottom=&#8221;yes&#8221; remove_border=&#8221;yes&#8221; el_class=&#8221;home-intro home-intro-dark&#8221; css=&#8221;.vc_custom_1555499835658{padding-top: 60px !important;padding-bottom: 60px !important;}&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#003d7f&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css_animation=&#8221;zoomIn&#8221;]\n<h2><strong>Com quem trabalhamos&#8230;<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<h4><strong>Nos orgulhamos em trabalhar com as principais empresas, arquitetos, consultores e empreiteiros do mundo para fornecer portas inovadoras e personalizadas para projetos premiados. Here are leading companies who have chosen Clark Door for their projects:<\/strong><\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50&#8243; custom_height_tablet=&#8221;40&#8243; custom_height_phone=&#8221;30&#8243;][vc_column_text]<style id=\"wp_carousel_dynamic_css14689\">.sp-wp-carousel-free-id-14689.wpcf-fancybox-wrapper .fancybox-bg{background: #0b0b0b;opacity: 0.8;}.sp-wp-carousel-free-id-14689.wpcf-fancybox-wrapper .fancybox-navigation .fancybox-button .wpcp-fancybox-nav-arrow i {color: #ccc;}.sp-wp-carousel-free-id-14689.wpcf-fancybox-wrapper .fancybox-navigation .fancybox-button .wpcp-fancybox-nav-arrow i:hover {color: #fff;}.sp-wp-carousel-free-id-14689.wpcf-fancybox-wrapper .fancybox-navigation .fancybox-button {background: #1e1e1e;}.sp-wp-carousel-free-id-14689.wpcf-fancybox-wrapper .fancybox-navigation .fancybox-button:hover {background: #1e1e1e;}#sp-wp-carousel-free-id-14689 .wpcp-swiper-dots {margin: 40px 0px 0px 0px;}.wpcp-wrapper-14689 .swiper-wrapper .swiper-slide-kenburn, .wpcp-wrapper-14689 .swiper-wrapper, .wpcp-wrapper-14689 .wpcpro-row{align-items: center;}#sp-wp-carousel-free-id-14689 .wpcp-single-item {box-shadow: 0px 0px 0px 0px #dddddd;transition: all .3s;margin: 0px;}#sp-wp-carousel-free-id-14689.swiper-flip .wpcp-single-item{margin: 0!important;}#sp-wp-carousel-free-id-14689 .wpcp-single-item:hover {box-shadow: 0px 0px 0px 0px #dddddd;}#sp-wp-carousel-free-id-14689.sp-wpcp-14689 .wpcp-single-item {border: 1px none #dddddd;}#sp-wp-carousel-free-id-14689.wpcp-carousel-section.sp-wpcp-14689 .swiper-button-prev,#sp-wp-carousel-free-id-14689.wpcp-carousel-section.sp-wpcp-14689 .swiper-button-next,#sp-wp-carousel-free-id-14689.wpcp-carousel-section.sp-wpcp-14689 .swiper-button-prev:hover,#sp-wp-carousel-free-id-14689.wpcp-carousel-section.sp-wpcp-14689 .swiper-button-next:hover {font-size: 18px ; font-weight: 400;}#sp-wp-carousel-free-id-14689.sp-wpcp-14689 .swiper-button-prev,#sp-wp-carousel-free-id-14689.sp-wpcp-14689 .swiper-button-next,#sp-wp-carousel-free-id-14689.sp-wpcp-14689 .swiper-button-prev:hover,#sp-wp-carousel-free-id-14689.sp-wpcp-14689 .swiper-button-next:hover {background: none;border: none;font-size: 30px;}#sp-wp-carousel-free-id-14689.sp-wpcp-14689 .swiper-button-prev i,#sp-wp-carousel-free-id-14689.sp-wpcp-14689 .swiper-button-next i {color: #aaa;}#sp-wp-carousel-free-id-14689.sp-wpcp-14689 .swiper-button-prev i:hover,#sp-wp-carousel-free-id-14689.sp-wpcp-14689 .swiper-button-next i:hover {color: #178087;} #sp-wp-carousel-free-id-14689.sp-wpcp-14689.wpcp-image-carousel .wpcp-single-item:hover img, #sp-wp-carousel-free-id-14689.sp-wpcp-14689.wpcp-post-carousel .wpcp-single-item:hover img, #sp-wp-carousel-free-id-14689.sp-wpcp-14689.wpcp-product-carousel .wpcp-single-item:hover img{-webkit-transform: scale(1.2);-moz-transform: scale(1.2);transform: scale(1.2);}@media screen and (max-width: 479px) {#sp-wp-carousel-free-id-14689.nav-vertical-center {padding: 0;margin:0;}#sp-wp-carousel-free-id-14689.nav-vertical-center .wpcp-next-button,#sp-wp-carousel-free-id-14689.nav-vertical-center .wpcp-prev-button {display: none;}}#sp-wp-carousel-free-id-14689 .wpcpro-row>[class*=\"wpcpro-col-\"] { padding: 0 10px; padding-bottom: 20px;} #sp-wp-carousel-free-id-14689 .swiper-slide .single-item-fade:not(:last-child) { margin-right: 20px;}@media (min-width: 480px) { .wpcpro-row .wpcpro-col-sm-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-sm-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-sm-2-5 { flex: 0 0 75%; max-width: 75%; } .wpcpro-row .wpcpro-col-sm-3 { flex: 0 0 33.333%; max-width: 33.333%; } .wpcpro-row .wpcpro-col-sm-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-sm-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-sm-6 { flex: 0 0 16.66666666666667%; max-width: 16.66666666666667%; } .wpcpro-row .wpcpro-col-sm-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-sm-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (max-width: 480px) { .wpcpro-row .wpcpro-col-xs-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-xs-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-xs-3 { flex: 0 0 33.222%; max-width: 33.222%; } .wpcpro-row .wpcpro-col-xs-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-xs-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-xs-6 { flex: 0 0 16.6667%; max-width: 16.6667%; } .wpcpro-row .wpcpro-col-xs-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-xs-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (min-width: 736px) { .wpcpro-row .wpcpro-col-md-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-md-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-md-2-5 { flex: 0 0 75%; max-width: 75%; } .wpcpro-row .wpcpro-col-md-3 { flex: 0 0 33.333%; max-width: 33.333%; } .wpcpro-row .wpcpro-col-md-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-md-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-md-6 { flex: 0 0 16.66666666666667%; max-width: 16.66666666666667%; } .wpcpro-row .wpcpro-col-md-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-md-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (min-width: 980px) { .wpcpro-row .wpcpro-col-lg-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-lg-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-lg-3 { flex: 0 0 33.222%; max-width: 33.222%; } .wpcpro-row .wpcpro-col-lg-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-lg-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-lg-6 { flex: 0 0 16.6667%; max-width: 16.6667%; } .wpcpro-row .wpcpro-col-lg-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-lg-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (min-width: 1200px) { .wpcpro-row .wpcpro-col-xl-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-xl-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-xl-3 { flex: 0 0 33.22222222%; max-width: 33.22222222%; } .wpcpro-row .wpcpro-col-xl-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-xl-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-xl-6 { flex: 0 0 16.66667%; max-width: 16.66667%; } .wpcpro-row .wpcpro-col-xl-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-xl-8 { flex: 0 0 12.5%; max-width: 12.5%; } }<\/style><div class=\"wpcp-carousel-wrapper wpcp-wrapper-14689\">\n\t<div id=\"wpcp-preloader-14689\" class=\"wpcp-carousel-preloader\"><img decoding=\"async\" data-src=\"https:\/\/www.clarkdoor.com\/wp-content\/plugins\/wp-carousel-free\/public\/css\/spinner.svg\" alt=\"Preloader Image\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" \/><\/div>\t<div class=\"wpcp-carousel-content-wrapper\">\n\t<div id=\"sp-wp-carousel-free-id-14689\" class=\"wpcp-carousel-section sp-wpcp-14689  nav-vertical-center wpcp-image-carousel wpcp-preloader wpcp-standard\" data-swiper='{ &quot;pagination_type&quot;: &quot;dots&quot;,&quot;accessibility&quot;:true, &quot;spaceBetween&quot;:20, &quot;arrows&quot;:true, &quot;freeMode&quot;: false, &quot;autoplay&quot;:true, &quot;effect&quot;: &quot;&quot;, &quot;centerMode&quot;: false, &quot;autoplaySpeed&quot;:2000, &quot;dots&quot;:false, &quot;infinite&quot;:true, &quot;speed&quot;:700, &quot;pauseOnHover&quot;:false,\n\t\t\t&quot;slidesToShow&quot;:{&quot;lg_desktop&quot;:5, &quot;desktop&quot;: 4, &quot;laptop&quot;: 3, &quot;tablet&quot;: 2, &quot;mobile&quot;: 1}, &quot;responsive&quot;:{&quot;desktop&quot;:1200, &quot;laptop&quot;: 980, &quot;tablet&quot;: 736, &quot;mobile&quot;: 480}, &quot;rtl&quot;:false, &quot;lazyLoad&quot;: &quot;false&quot;, &quot;swipe&quot;: true, &quot;draggable&quot;: true, &quot;swipeToSlide&quot;:false }' dir=\"ltr\">\n\t\t<div class=\"swiper-wrapper\">\n\t\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2023\/06\/Untitled-3-1.jpg\" alt=\"Rolls Royce\" width=\"200\" height=\"200\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2019\/04\/logo-wb.png\" alt=\"logo-wb\" width=\"87\" height=\"100\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/11\/bbc-logo.png\" alt=\"bbc-logo\" width=\"150\" height=\"150\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/11\/download.png\" alt=\"download\" width=\"266\" height=\"190\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2019\/04\/logo-tate.png\" alt=\"logo-tate\" width=\"213\" height=\"100\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2019\/04\/logo-pinewood.png\" alt=\"logo-pinewood\" width=\"323\" height=\"100\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2019\/04\/logo-roh.png\" alt=\"logo-roh\" width=\"70\" height=\"100\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/11\/unilever-logo.png\" alt=\"unilever-logo\" width=\"150\" height=\"150\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/11\/sky-logo.png\" alt=\"sky-logo\" width=\"150\" height=\"150\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/11\/Siemens-Logo.png\" alt=\"Siemens-Logo\" width=\"150\" height=\"150\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/11\/london-underground-logo.png\" alt=\"london-underground-logo\" width=\"150\" height=\"150\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/11\/royal-air-force-logo.png\" alt=\"royal-air-force-logo\" width=\"150\" height=\"150\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/11\/p-and-g-logo.png\" alt=\"p-and-g-logo\" width=\"150\" height=\"150\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/11\/ibm-logo.png\" alt=\"ibm-logo\" width=\"150\" height=\"150\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2022\/12\/Red-Bull-logo-1-e1687956378355.png\" alt=\"Red-Bull-logo\" width=\"200\" height=\"113\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2019\/04\/logo-itv.png\" alt=\"logo-itv\" width=\"161\" height=\"80\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2019\/04\/logo-ford.png\" alt=\"logo-ford\" width=\"185\" height=\"100\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2025\/12\/NFL-media-Logo.png\" alt=\"NFL media Logo\" width=\"288\" height=\"175\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2025\/12\/PACNYCTRANS-Logo.png\" alt=\"PACNYCTRANS Logo\" width=\"250\" height=\"150\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<div class=\"wpcp-slide-image\">\n\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2025\/12\/Shinfield.png\" alt=\"Shinfield\" width=\"510\" height=\"99\">\t<\/div>\n\t\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t\t<!-- If we need navigation buttons -->\n\t\t\t\t\t<div class=\"wpcp-prev-button swiper-button-prev\"><i class=\"fa fa-angle-left\"><\/i><\/div>\n\t\t\t<div class=\"wpcp-next-button swiper-button-next\"><i class=\"fa fa-angle-right\"><\/i><\/div>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; parallax=&#8221;content-moving&#8221; parallax_image=&#8221;6442&#8243; wrap_container=&#8221;yes&#8221; el_class=&#8221;half-right no-padding border-top-1&#8243; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-18257","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contacte-Nos<\/title>\n<meta name=\"description\" content=\"Entre em contato conosco por telefone, email ou preencha o formul\u00e1rio de contato abaixo se precisar de mais informa\u00e7\u00f5es sobre a nossa ampla gama de portas especiais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contacte-Nos\" \/>\n<meta property=\"og:description\" content=\"Entre em contato conosco por telefone, email ou preencha o formul\u00e1rio de contato abaixo se precisar de mais informa\u00e7\u00f5es sobre a nossa ampla gama de portas especiais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/\" \/>\n<meta property=\"og:site_name\" content=\"Clark Door\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/clarkdoorltd\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-19T15:27:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2023\/04\/R0A9205.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/\",\"url\":\"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/\",\"name\":\"Contacte-Nos\",\"isPartOf\":{\"@id\":\"https:\/\/www.clarkdoor.com\/pt-br\/#website\"},\"datePublished\":\"2016-06-14T05:15:58+00:00\",\"dateModified\":\"2023-06-19T15:27:34+00:00\",\"description\":\"Entre em contato conosco por telefone, email ou preencha o formul\u00e1rio de contato abaixo se precisar de mais informa\u00e7\u00f5es sobre a nossa ampla gama de portas especiais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.clarkdoor.com\/pt-br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contactar a Clark Door\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.clarkdoor.com\/pt-br\/#website\",\"url\":\"https:\/\/www.clarkdoor.com\/pt-br\/\",\"name\":\"Clark Door The Market Leader in Special Purpose Door Systems\",\"description\":\"The Market Leader in Special Purpose Door Systems\",\"alternateName\":\"Clark Door\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.clarkdoor.com\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contacte-Nos","description":"Entre em contato conosco por telefone, email ou preencha o formul\u00e1rio de contato abaixo se precisar de mais informa\u00e7\u00f5es sobre a nossa ampla gama de portas especiais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/","og_locale":"pt_BR","og_type":"article","og_title":"Contacte-Nos","og_description":"Entre em contato conosco por telefone, email ou preencha o formul\u00e1rio de contato abaixo se precisar de mais informa\u00e7\u00f5es sobre a nossa ampla gama de portas especiais.","og_url":"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/","og_site_name":"Clark Door","article_publisher":"https:\/\/www.facebook.com\/clarkdoorltd","article_modified_time":"2023-06-19T15:27:34+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.clarkdoor.com\/wp-content\/uploads\/2023\/04\/R0A9205.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/","url":"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/","name":"Contacte-Nos","isPartOf":{"@id":"https:\/\/www.clarkdoor.com\/pt-br\/#website"},"datePublished":"2016-06-14T05:15:58+00:00","dateModified":"2023-06-19T15:27:34+00:00","description":"Entre em contato conosco por telefone, email ou preencha o formul\u00e1rio de contato abaixo se precisar de mais informa\u00e7\u00f5es sobre a nossa ampla gama de portas especiais.","breadcrumb":{"@id":"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.clarkdoor.com\/pt-br\/contactar-a-clark-door\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.clarkdoor.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Contactar a Clark Door"}]},{"@type":"WebSite","@id":"https:\/\/www.clarkdoor.com\/pt-br\/#website","url":"https:\/\/www.clarkdoor.com\/pt-br\/","name":"Clark Door The Market Leader in Special Purpose Door Systems","description":"The Market Leader in Special Purpose Door Systems","alternateName":"Clark Door","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clarkdoor.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.clarkdoor.com\/pt-br\/wp-json\/wp\/v2\/pages\/18257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clarkdoor.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.clarkdoor.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.clarkdoor.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clarkdoor.com\/pt-br\/wp-json\/wp\/v2\/comments?post=18257"}],"version-history":[{"count":8,"href":"https:\/\/www.clarkdoor.com\/pt-br\/wp-json\/wp\/v2\/pages\/18257\/revisions"}],"predecessor-version":[{"id":18284,"href":"https:\/\/www.clarkdoor.com\/pt-br\/wp-json\/wp\/v2\/pages\/18257\/revisions\/18284"}],"wp:attachment":[{"href":"https:\/\/www.clarkdoor.com\/pt-br\/wp-json\/wp\/v2\/media?parent=18257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}